{"id":60394,"date":"2026-03-27T12:05:28","date_gmt":"2026-03-27T11:05:28","guid":{"rendered":"https:\/\/www.alveus.eu\/?p=60394"},"modified":"2026-04-28T16:05:18","modified_gmt":"2026-04-28T14:05:18","slug":"aromi-te-biologici","status":"publish","type":"post","link":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/","title":{"rendered":"Aromi nei t\u00e8 biologici: cosa sono e perch\u00e9 sono importanti"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"60394\" class=\"elementor elementor-60394 elementor-60356\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41a2d465 e-con-full e-flex e-con e-parent\" data-id=\"41a2d465\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19e7ee55 elementor-widget elementor-widget-text-editor\" data-id=\"19e7ee55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Se lavori nel settore del t\u00e8, \u00e8 molto probabile che ti sia imbattuto pi\u00f9 di una volta nel termine <\/span><b>aromi 95\/5 o FTNF<\/b><span style=\"font-weight: 400;\">. Si tratta degli aromi utilizzati nei t\u00e8 aromatizzati certificati come biologici.<\/span><\/p><p><span style=\"font-weight: 400;\">In questi prodotti non basta che l&#8217;aroma risulti gradevole in tazza. Contano anche la sua provenienza, il modo in cui pu\u00f2 essere dichiarato e ci\u00f2 che apporta al posizionamento del prodotto.<\/span><\/p><p><span style=\"font-weight: 400;\">Parlare di aromi 95\/5 significa parlare di formulazione, di normative, di trasparenza e, in molti casi, anche di valore percepito.<\/span><\/p><p><span style=\"font-weight: 400;\">In questo post ti forniremo tutte le informazioni su questo tipo di aroma, affinch\u00e9 tu ne comprenda l&#8217;importanza, sappia esattamente cosa stai acquistando e possa rispondere con chiarezza alle domande dei tuoi clienti.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e5d0e86 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"2e5d0e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;exclude_headings_by_selector&quot;:&quot;.elementor-grid .elementor-heading-title&quot;,&quot;no_headings_message&quot;:&quot;No headings were found on this page.&quot;,&quot;marker_view&quot;:&quot;numbers&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<div class=\"elementor-toc__header-title\">\n\t\t\t\tSommario\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__2e5d0e86\" aria-expanded=\"true\" aria-label=\"Apri l&#039;indice dei contenuti\"><i aria-hidden=\"true\" class=\"alveus alveus-arrow\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__2e5d0e86\" aria-expanded=\"true\" aria-label=\"Chiudi l&#039;indice dei contenuti\"><i aria-hidden=\"true\" class=\"alveus alveus-close\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__2e5d0e86\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1de66c elementor-widget elementor-widget-shortcode\" data-id=\"d1de66c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"51141\" class=\"elementor elementor-51141 elementor-51052 elementor-51052\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-3039963 e-con-full e-flex e-con e-parent\" data-id=\"3039963\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4351092 e-con-full e-flex e-con e-child\" data-id=\"4351092\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2090423 elementor-widget elementor-widget-heading\" data-id=\"2090423\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ricevi 10 campioni gratuiti<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b4106c elementor-widget elementor-widget-heading\" data-id=\"1b4106c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Esclusivamente per i professionisti del t\u00e8<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6cc423 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c6cc423\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#request-catalogue\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RICHIEDERE CATALOGO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92c569c e-con-full e-flex e-con e-child\" data-id=\"92c569c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82c5156 elementor-widget elementor-widget-image\" data-id=\"82c5156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"863\" height=\"343\" src=\"https:\/\/www.alveus.eu\/wp-content\/uploads\/cta-catalogues.png\" class=\"attachment-large size-large wp-image-51123\" alt=\"\" srcset=\"https:\/\/www.alveus.eu\/wp-content\/uploads\/cta-catalogues.png 863w, https:\/\/www.alveus.eu\/wp-content\/uploads\/cta-catalogues-300x119.png 300w, https:\/\/www.alveus.eu\/wp-content\/uploads\/cta-catalogues-768x305.png 768w\" sizes=\"(max-width: 863px) 100vw, 863px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bc12f47 elementor-widget elementor-widget-heading\" data-id=\"2bc12f47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Che cos'\u00e8 un aroma 95\/5\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49a89da1 elementor-widget elementor-widget-text-editor\" data-id=\"49a89da1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Per capire bene cos&#8217;\u00e8 un aroma 95\/5, \u00e8 opportuno chiarire innanzitutto cos&#8217;\u00e8 un aroma naturale.<\/span><\/p><p><span style=\"font-weight: 400;\">Un aroma naturale \u00e8 quello che proviene dalla natura, ovvero non \u00e8 stato creato sinteticamente dall&#8217;uomo. Tuttavia, ci\u00f2 non significa necessariamente che provenga dall&#8217;ingrediente che il consumatore immagina. Ad esempio, un aroma di vaniglia non deve necessariamente essere ottenuto direttamente dal baccello di vaniglia; pu\u00f2 anche provenire da altre fonti naturali<\/span><\/p><p><span style=\"font-weight: 400;\">\u00c8 qui che entra in gioco <\/span><b>l&#8217;aroma 95\/5. Si tratta di un sottotipo di aroma naturale <\/b><span style=\"font-weight: 400;\">in cui almeno il 95% della componente aromatica proviene dal frutto, dalla pianta, dalla spezia o dall&#8217;ingrediente indicato.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Il restante 5% pu\u00f2 provenire anch&#8217;esso da fonti naturali, ma non deve alterare il carattere del sapore principale.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Questa logica \u00e8 in linea con l&#8217;articolo 16 del Regolamento (CE) 1334\/2008, che riserva menzioni come &#8220;<\/span><i><span style=\"font-weight: 400;\">aroma naturale di <\/span><\/i><span style=\"font-weight: 400;\">fragola&#8221; ai casi in cui almeno il 95% della componente aromatizzante provenga dalla fonte menzionata, ovvero la fragola.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a98912 e-flex e-con-boxed e-con e-child\" data-id=\"3a98912\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f26a55a elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f26a55a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewBox=\"0 0 192 192\"><defs><style> .cls-1 { fill: none; } .cls-2 { fill: #1d1d1b; } <\/style><\/defs><g id=\"medida\"><g><rect class=\"cls-1\" width=\"192\" height=\"192\"><\/rect><g><path class=\"cls-2\" d=\"M50.98,81.76h-15.81c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h15.81c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M64.9,53.79c1.37-1.37,1.37-3.58,0-4.95l-10.12-10.12c-1.37-1.37-3.58-1.37-4.95,0-1.37,1.37-1.37,3.58,0,4.95l10.12,10.12c.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03Z\"><\/path><path class=\"cls-2\" d=\"M145.27,38.72c-1.37-1.37-3.58-1.37-4.95,0l-10.12,10.12c-1.37,1.37-1.37,3.58,0,4.95,.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03l10.12-10.12c1.37-1.37,1.37-3.58,0-4.95Z\"><\/path><path class=\"cls-2\" d=\"M97.75,42c1.93,0,3.5-1.57,3.5-3.5v-14.15c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5v14.15c0,1.93,1.57,3.5,3.5,3.5Z\"><\/path><path class=\"cls-2\" d=\"M156.83,81.76h-14.03c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h14.03c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M97.75,48.42c-19.84,0-35.98,16.14-35.98,35.98,0,5.06,.99,9.78,3.03,14.44,.96,2.2,2.35,4.65,3.82,7.25,2.14,3.78,4.57,8.07,5.66,11.69,5.01,16.67,2.59,32.29,2.56,32.45l-.05,.56c0,11.22,9.13,20.36,20.36,20.36s20.36-9.13,20.36-20.36l-.04-.56c-.01-.09-.83-5.44-.21-13.48,.08-.29,.13-.58,.13-.89,0-.1-.02-.19-.03-.29,.48-5.16,1.55-11.3,3.76-17.81,1.37-4.04,4.12-8.95,6.55-13.28,1.09-1.95,2.12-3.79,2.96-5.44,2.75-5.36,3.12-10.41,3.12-14.64,0-19.84-16.14-35.98-35.98-35.98Zm12.3,90.94c-.16,4.07,0,7.32,.19,9.41h-26.18c.21-2.1,.44-5.36,.39-9.41h25.6Zm-12.91,24.79c-5.6,0-10.4-3.48-12.38-8.38h24.76c-1.98,4.9-6.78,8.38-12.38,8.38Zm27.24-68.3c-.79,1.54-1.79,3.32-2.84,5.21-2.57,4.6-5.49,9.8-7.07,14.45-2.06,6.07-3.23,11.82-3.85,16.86h-9.68c.34-.54,.54-1.17,.54-1.86v-19.97c5.79-1.55,10.07-6.82,10.07-13.1,0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,3.62-2.95,6.57-6.57,6.57s-6.57-2.95-6.57-6.57c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,6.27,4.28,11.55,10.07,13.1v19.97c0,.68,.2,1.32,.54,1.86h-10.93c-.44-5.05-1.37-10.74-3.14-16.6-1.31-4.37-3.95-9.02-6.27-13.12-1.38-2.44-2.68-4.74-3.5-6.6-1.64-3.76-2.44-7.56-2.44-11.64,0-15.98,13-28.98,28.98-28.98s28.98,13,28.98,28.98c0,4.87-.68,8.19-2.35,11.45Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eca0d44 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"eca0d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">In parole povere: se in una ricetta compare \"aroma naturale di mango\", quel sapore deve provenire prevalentemente dal mango stesso, non da un'altra materia prima naturale che ne imiti il profilo.\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abbe01c elementor-widget elementor-widget-heading\" data-id=\"abbe01c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cosa significano gli aromi FTNF\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9b3ade elementor-widget elementor-widget-text-editor\" data-id=\"e9b3ade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">In molti casi, gli aromi 95\/5 compaiono anche associati al termine FTNF. Queste sigle derivano da <\/span><i><span style=\"font-weight: 400;\">From The Named Fruit<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p><p><span style=\"font-weight: 400;\">Sebbene vengano spesso citati insieme, non sono esattamente la stessa cosa. In un aroma 95\/5, almeno il 95% dell&#8217;aroma proviene dall&#8217;ingrediente indicato. In un aroma FTNF, il 100% della sostanza aromatica proviene da quell&#8217;ingrediente.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">In pratica, l&#8217;FTNF funge da base a partire dalla quale \u00e8 possibile formulare successivamente un aroma 95\/5.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9270170 e-flex e-con-boxed e-con e-child\" data-id=\"9270170\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31649c3 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"31649c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewBox=\"0 0 192 192\"><defs><style> .cls-1 { fill: none; } .cls-2 { fill: #1d1d1b; } <\/style><\/defs><g id=\"medida\"><g><rect class=\"cls-1\" width=\"192\" height=\"192\"><\/rect><g><path class=\"cls-2\" d=\"M50.98,81.76h-15.81c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h15.81c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M64.9,53.79c1.37-1.37,1.37-3.58,0-4.95l-10.12-10.12c-1.37-1.37-3.58-1.37-4.95,0-1.37,1.37-1.37,3.58,0,4.95l10.12,10.12c.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03Z\"><\/path><path class=\"cls-2\" d=\"M145.27,38.72c-1.37-1.37-3.58-1.37-4.95,0l-10.12,10.12c-1.37,1.37-1.37,3.58,0,4.95,.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03l10.12-10.12c1.37-1.37,1.37-3.58,0-4.95Z\"><\/path><path class=\"cls-2\" d=\"M97.75,42c1.93,0,3.5-1.57,3.5-3.5v-14.15c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5v14.15c0,1.93,1.57,3.5,3.5,3.5Z\"><\/path><path class=\"cls-2\" d=\"M156.83,81.76h-14.03c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h14.03c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M97.75,48.42c-19.84,0-35.98,16.14-35.98,35.98,0,5.06,.99,9.78,3.03,14.44,.96,2.2,2.35,4.65,3.82,7.25,2.14,3.78,4.57,8.07,5.66,11.69,5.01,16.67,2.59,32.29,2.56,32.45l-.05,.56c0,11.22,9.13,20.36,20.36,20.36s20.36-9.13,20.36-20.36l-.04-.56c-.01-.09-.83-5.44-.21-13.48,.08-.29,.13-.58,.13-.89,0-.1-.02-.19-.03-.29,.48-5.16,1.55-11.3,3.76-17.81,1.37-4.04,4.12-8.95,6.55-13.28,1.09-1.95,2.12-3.79,2.96-5.44,2.75-5.36,3.12-10.41,3.12-14.64,0-19.84-16.14-35.98-35.98-35.98Zm12.3,90.94c-.16,4.07,0,7.32,.19,9.41h-26.18c.21-2.1,.44-5.36,.39-9.41h25.6Zm-12.91,24.79c-5.6,0-10.4-3.48-12.38-8.38h24.76c-1.98,4.9-6.78,8.38-12.38,8.38Zm27.24-68.3c-.79,1.54-1.79,3.32-2.84,5.21-2.57,4.6-5.49,9.8-7.07,14.45-2.06,6.07-3.23,11.82-3.85,16.86h-9.68c.34-.54,.54-1.17,.54-1.86v-19.97c5.79-1.55,10.07-6.82,10.07-13.1,0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,3.62-2.95,6.57-6.57,6.57s-6.57-2.95-6.57-6.57c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,6.27,4.28,11.55,10.07,13.1v19.97c0,.68,.2,1.32,.54,1.86h-10.93c-.44-5.05-1.37-10.74-3.14-16.6-1.31-4.37-3.95-9.02-6.27-13.12-1.38-2.44-2.68-4.74-3.5-6.6-1.64-3.76-2.44-7.56-2.44-11.64,0-15.98,13-28.98,28.98-28.98s28.98,13,28.98,28.98c0,4.87-.68,8.19-2.35,11.45Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d564465 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"d564465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Per un professionista del t\u00e8, questa differenza \u00e8 utile perch\u00e9 aiuta a comprendere meglio l'origine dell'aroma e il modo in cui \u00e8 possibile elaborare una ricetta aromatizzata che rispetti maggiormente l'ingrediente dichiarato.\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cba72a elementor-widget elementor-widget-heading\" data-id=\"3cba72a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Come riconoscerli in una ricetta o in un elenco di ingredienti\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6adbb elementor-widget elementor-widget-text-editor\" data-id=\"ad6adbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questo punto \u00e8 particolarmente utile per negozi, marchi e distributori che hanno bisogno di leggere bene una scheda tecnica o di spiegare un prodotto al cliente finale.<\/span><\/p><p><span style=\"font-weight: 400;\">Quando un t\u00e8 include semplicemente &#8220;aroma naturale&#8221; o &#8220;aromi naturali&#8221;, ci\u00f2 non significa necessariamente che il sapore provenga dall&#8217;ingrediente che il consumatore ha in mente. Potrebbe trattarsi di una combinazione di diverse fonti naturali.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d742e9c e-flex e-con-boxed e-con e-child\" data-id=\"d742e9c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f17fc3b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f17fc3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewBox=\"0 0 192 192\"><defs><style> .cls-1 { fill: none; } .cls-2 { fill: #1d1d1b; } <\/style><\/defs><g id=\"medida\"><g><rect class=\"cls-1\" width=\"192\" height=\"192\"><\/rect><g><path class=\"cls-2\" d=\"M50.98,81.76h-15.81c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h15.81c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M64.9,53.79c1.37-1.37,1.37-3.58,0-4.95l-10.12-10.12c-1.37-1.37-3.58-1.37-4.95,0-1.37,1.37-1.37,3.58,0,4.95l10.12,10.12c.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03Z\"><\/path><path class=\"cls-2\" d=\"M145.27,38.72c-1.37-1.37-3.58-1.37-4.95,0l-10.12,10.12c-1.37,1.37-1.37,3.58,0,4.95,.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03l10.12-10.12c1.37-1.37,1.37-3.58,0-4.95Z\"><\/path><path class=\"cls-2\" d=\"M97.75,42c1.93,0,3.5-1.57,3.5-3.5v-14.15c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5v14.15c0,1.93,1.57,3.5,3.5,3.5Z\"><\/path><path class=\"cls-2\" d=\"M156.83,81.76h-14.03c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h14.03c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M97.75,48.42c-19.84,0-35.98,16.14-35.98,35.98,0,5.06,.99,9.78,3.03,14.44,.96,2.2,2.35,4.65,3.82,7.25,2.14,3.78,4.57,8.07,5.66,11.69,5.01,16.67,2.59,32.29,2.56,32.45l-.05,.56c0,11.22,9.13,20.36,20.36,20.36s20.36-9.13,20.36-20.36l-.04-.56c-.01-.09-.83-5.44-.21-13.48,.08-.29,.13-.58,.13-.89,0-.1-.02-.19-.03-.29,.48-5.16,1.55-11.3,3.76-17.81,1.37-4.04,4.12-8.95,6.55-13.28,1.09-1.95,2.12-3.79,2.96-5.44,2.75-5.36,3.12-10.41,3.12-14.64,0-19.84-16.14-35.98-35.98-35.98Zm12.3,90.94c-.16,4.07,0,7.32,.19,9.41h-26.18c.21-2.1,.44-5.36,.39-9.41h25.6Zm-12.91,24.79c-5.6,0-10.4-3.48-12.38-8.38h24.76c-1.98,4.9-6.78,8.38-12.38,8.38Zm27.24-68.3c-.79,1.54-1.79,3.32-2.84,5.21-2.57,4.6-5.49,9.8-7.07,14.45-2.06,6.07-3.23,11.82-3.85,16.86h-9.68c.34-.54,.54-1.17,.54-1.86v-19.97c5.79-1.55,10.07-6.82,10.07-13.1,0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,3.62-2.95,6.57-6.57,6.57s-6.57-2.95-6.57-6.57c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,6.27,4.28,11.55,10.07,13.1v19.97c0,.68,.2,1.32,.54,1.86h-10.93c-.44-5.05-1.37-10.74-3.14-16.6-1.31-4.37-3.95-9.02-6.27-13.12-1.38-2.44-2.68-4.74-3.5-6.6-1.64-3.76-2.44-7.56-2.44-11.64,0-15.98,13-28.98,28.98-28.98s28.98,13,28.98,28.98c0,4.87-.68,8.19-2.35,11.45Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcc3f93 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"bcc3f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Esistono aromi naturali che, per ricreare un sapore di arancia acida, utilizzano aroma di arancia con aroma di limone. Entrambi sono naturali, ma non vengono dichiarati entrambi i frutti. \n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6767ff elementor-widget elementor-widget-text-editor\" data-id=\"d6767ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Al contrario, quando compare una menzione specifica del tipo <\/span><i><span style=\"font-weight: 400;\">\u201caroma naturale di <\/span><\/i><span style=\"font-weight: 400;\">fragola\u201d, <\/span><i><span style=\"font-weight: 400;\">\u201caroma naturale di <\/span><\/i><span style=\"font-weight: 400;\">limone\u201d o <\/span><i><span style=\"font-weight: 400;\">\u201caroma naturale di <\/span><\/i><span style=\"font-weight: 400;\">vaniglia\u201d, tale denominazione richiede un rapporto molto pi\u00f9 diretto tra il sapore e la materia prima indicata. Proprio per questo, gli aromi 95\/5 offrono un maggiore grado di trasparenza.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a94bbc elementor-widget elementor-widget-image\" data-id=\"6a94bbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_b.jpg\" class=\"attachment-large size-large wp-image-60375\" alt=\"aromi t\u00e8 biologici\" srcset=\"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_b.jpg 900w, https:\/\/www.alveus.eu\/wp-content\/uploads\/117_b-300x200.jpg 300w, https:\/\/www.alveus.eu\/wp-content\/uploads\/117_b-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99c6af8 elementor-widget elementor-widget-heading\" data-id=\"99c6af8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perch\u00e9 si utilizza questo aroma nei t\u00e8 biologici aromatizzati\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2327cb elementor-widget elementor-widget-text-editor\" data-id=\"d2327cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">In Europa, l&#8217;uso degli aromi nei prodotti biologici \u00e8 soggetto a un quadro normativo pi\u00f9 rigoroso rispetto ai prodotti convenzionali.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">La normativa UE sulla produzione biologica applica regole specifiche agli alimenti trasformati e le linee guida tecniche della Commissione Europea hanno sottolineato che, nell&#8217;ambito del biologico, gli aromi naturali ammessi devono allinearsi alle categorie degli articoli 16.4 e 16.5 del Regolamento 1334\/2008.<\/span><\/p><p><span style=\"font-weight: 400;\">Ecco perch\u00e9, nel t\u00e8 biologico aromatizzato, gli aromi 95\/5 rivestono un ruolo cos\u00ec importante. Non si tratta di un semplice dettaglio tecnico. Fanno parte del modo in cui viene realizzato un prodotto che deve essere coerente con ci\u00f2 che promette, con come viene etichettato e con ci\u00f2 che si aspetta un cliente alla ricerca di una gamma BIO. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d049d75 e-flex e-con-boxed e-con e-child\" data-id=\"d049d75\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3494962 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3494962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewBox=\"0 0 192 192\"><defs><style> .cls-1 { fill: none; } .cls-2 { fill: #1d1d1b; } <\/style><\/defs><g id=\"medida\"><g><rect class=\"cls-1\" width=\"192\" height=\"192\"><\/rect><g><path class=\"cls-2\" d=\"M50.98,81.76h-15.81c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h15.81c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M64.9,53.79c1.37-1.37,1.37-3.58,0-4.95l-10.12-10.12c-1.37-1.37-3.58-1.37-4.95,0-1.37,1.37-1.37,3.58,0,4.95l10.12,10.12c.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03Z\"><\/path><path class=\"cls-2\" d=\"M145.27,38.72c-1.37-1.37-3.58-1.37-4.95,0l-10.12,10.12c-1.37,1.37-1.37,3.58,0,4.95,.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03l10.12-10.12c1.37-1.37,1.37-3.58,0-4.95Z\"><\/path><path class=\"cls-2\" d=\"M97.75,42c1.93,0,3.5-1.57,3.5-3.5v-14.15c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5v14.15c0,1.93,1.57,3.5,3.5,3.5Z\"><\/path><path class=\"cls-2\" d=\"M156.83,81.76h-14.03c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h14.03c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M97.75,48.42c-19.84,0-35.98,16.14-35.98,35.98,0,5.06,.99,9.78,3.03,14.44,.96,2.2,2.35,4.65,3.82,7.25,2.14,3.78,4.57,8.07,5.66,11.69,5.01,16.67,2.59,32.29,2.56,32.45l-.05,.56c0,11.22,9.13,20.36,20.36,20.36s20.36-9.13,20.36-20.36l-.04-.56c-.01-.09-.83-5.44-.21-13.48,.08-.29,.13-.58,.13-.89,0-.1-.02-.19-.03-.29,.48-5.16,1.55-11.3,3.76-17.81,1.37-4.04,4.12-8.95,6.55-13.28,1.09-1.95,2.12-3.79,2.96-5.44,2.75-5.36,3.12-10.41,3.12-14.64,0-19.84-16.14-35.98-35.98-35.98Zm12.3,90.94c-.16,4.07,0,7.32,.19,9.41h-26.18c.21-2.1,.44-5.36,.39-9.41h25.6Zm-12.91,24.79c-5.6,0-10.4-3.48-12.38-8.38h24.76c-1.98,4.9-6.78,8.38-12.38,8.38Zm27.24-68.3c-.79,1.54-1.79,3.32-2.84,5.21-2.57,4.6-5.49,9.8-7.07,14.45-2.06,6.07-3.23,11.82-3.85,16.86h-9.68c.34-.54,.54-1.17,.54-1.86v-19.97c5.79-1.55,10.07-6.82,10.07-13.1,0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,3.62-2.95,6.57-6.57,6.57s-6.57-2.95-6.57-6.57c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,6.27,4.28,11.55,10.07,13.1v19.97c0,.68,.2,1.32,.54,1.86h-10.93c-.44-5.05-1.37-10.74-3.14-16.6-1.31-4.37-3.95-9.02-6.27-13.12-1.38-2.44-2.68-4.74-3.5-6.6-1.64-3.76-2.44-7.56-2.44-11.64,0-15.98,13-28.98,28.98-28.98s28.98,13,28.98,28.98c0,4.87-.68,8.19-2.35,11.45Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-604429f elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"604429f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">\u00c8 bene ricordare che il 95\/5 non \u00e8 l'unico strumento aromatico sul mercato. Nel lavoro con le ricette BIO possono intervenire anche estratti e oli essenziali biologici, a seconda del tipo di prodotto e del risultato che si desidera ottenere. <\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e7436ba elementor-widget elementor-widget-heading\" data-id=\"1e7436ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cosa \u00e8 cambiato con la normativa biologica\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29af8a elementor-widget elementor-widget-text-editor\" data-id=\"d29af8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Prima del 2022, gli aromi non erano trattati allo stesso modo nell&#8217;ambito del biologico, tra l&#8217;altro perch\u00e9 non erano considerati prodotti agricoli nello stesso senso in cui oggi \u00e8 richiesto nella pratica del settore.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Questo cambiamento ha portato a rafforzare i criteri relativi ai tipi di aromi che potevano essere utilizzati nei prodotti biologici trasformati.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">In pratica, ci\u00f2 ha reso pi\u00f9 impegnativo il lavoro con i t\u00e8 biologici aromatizzati. Non si tratta pi\u00f9 solo di ottenere un profilo aromatico attraente, ma di farlo all&#8217;interno di un quadro pi\u00f9 limitato, trasparente e molto pi\u00f9 controllato.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14f97de elementor-widget elementor-widget-heading\" data-id=\"14f97de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Un chiarimento importante sul famoso \u201c5 %\u201d\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b71a72 elementor-widget elementor-widget-text-editor\" data-id=\"8b71a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Su questo punto c&#8217;\u00e8 spesso molta confusione, quindi vale la pena soffermarsi un attimo.<\/span><\/p><p><span style=\"font-weight: 400;\">Da un lato, il \u201c95\/5\u201d si riferisce alla composizione dell\u2019aroma stesso. Cio\u00e8, a quanta parte di quella componente aromatica proviene dall\u2019ingrediente indicato.<\/span><\/p><p><span style=\"font-weight: 400;\">Nel caso in cui gli aromi non siano certificati come biologici, come pu\u00f2 accadere con un olio biologico di bergamotto o un estratto biologico di vaniglia, nelle miscele di t\u00e8 sono ammessi solo aromi 95\/5 fino a un massimo del 5%.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">In altre parole, non \u00e8 possibile utilizzare l&#8217;8% di aroma per intensificarne il sapore. Il limite massimo \u00e8 del 5%.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab7cbe3 e-flex e-con-boxed e-con e-child\" data-id=\"ab7cbe3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09fbd7f elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"09fbd7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewBox=\"0 0 192 192\"><defs><style> .cls-1 { fill: none; } .cls-2 { fill: #1d1d1b; } <\/style><\/defs><g id=\"medida\"><g><rect class=\"cls-1\" width=\"192\" height=\"192\"><\/rect><g><path class=\"cls-2\" d=\"M50.98,81.76h-15.81c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h15.81c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M64.9,53.79c1.37-1.37,1.37-3.58,0-4.95l-10.12-10.12c-1.37-1.37-3.58-1.37-4.95,0-1.37,1.37-1.37,3.58,0,4.95l10.12,10.12c.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03Z\"><\/path><path class=\"cls-2\" d=\"M145.27,38.72c-1.37-1.37-3.58-1.37-4.95,0l-10.12,10.12c-1.37,1.37-1.37,3.58,0,4.95,.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03l10.12-10.12c1.37-1.37,1.37-3.58,0-4.95Z\"><\/path><path class=\"cls-2\" d=\"M97.75,42c1.93,0,3.5-1.57,3.5-3.5v-14.15c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5v14.15c0,1.93,1.57,3.5,3.5,3.5Z\"><\/path><path class=\"cls-2\" d=\"M156.83,81.76h-14.03c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h14.03c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M97.75,48.42c-19.84,0-35.98,16.14-35.98,35.98,0,5.06,.99,9.78,3.03,14.44,.96,2.2,2.35,4.65,3.82,7.25,2.14,3.78,4.57,8.07,5.66,11.69,5.01,16.67,2.59,32.29,2.56,32.45l-.05,.56c0,11.22,9.13,20.36,20.36,20.36s20.36-9.13,20.36-20.36l-.04-.56c-.01-.09-.83-5.44-.21-13.48,.08-.29,.13-.58,.13-.89,0-.1-.02-.19-.03-.29,.48-5.16,1.55-11.3,3.76-17.81,1.37-4.04,4.12-8.95,6.55-13.28,1.09-1.95,2.12-3.79,2.96-5.44,2.75-5.36,3.12-10.41,3.12-14.64,0-19.84-16.14-35.98-35.98-35.98Zm12.3,90.94c-.16,4.07,0,7.32,.19,9.41h-26.18c.21-2.1,.44-5.36,.39-9.41h25.6Zm-12.91,24.79c-5.6,0-10.4-3.48-12.38-8.38h24.76c-1.98,4.9-6.78,8.38-12.38,8.38Zm27.24-68.3c-.79,1.54-1.79,3.32-2.84,5.21-2.57,4.6-5.49,9.8-7.07,14.45-2.06,6.07-3.23,11.82-3.85,16.86h-9.68c.34-.54,.54-1.17,.54-1.86v-19.97c5.79-1.55,10.07-6.82,10.07-13.1,0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,3.62-2.95,6.57-6.57,6.57s-6.57-2.95-6.57-6.57c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,6.27,4.28,11.55,10.07,13.1v19.97c0,.68,.2,1.32,.54,1.86h-10.93c-.44-5.05-1.37-10.74-3.14-16.6-1.31-4.37-3.95-9.02-6.27-13.12-1.38-2.44-2.68-4.74-3.5-6.6-1.64-3.76-2.44-7.56-2.44-11.64,0-15.98,13-28.98,28.98-28.98s28.98,13,28.98,28.98c0,4.87-.68,8.19-2.35,11.45Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9b1113 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"f9b1113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Questo \u00e8 importante perch\u00e9 aiuta a capire due cose. La prima \u00e8 che l'aroma 95\/5 non equivale a \"molto aroma\", ma a un'origine pi\u00f9 definita dello stesso. La seconda: un t\u00e8 biologico aromatizzato ben formulato ha bisogno di equilibrio, non di eccesso.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8502d15 elementor-widget elementor-widget-heading\" data-id=\"8502d15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La difficolt\u00e0 di lavorare con questi aromi FTNF\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a676bd2 elementor-widget elementor-widget-text-editor\" data-id=\"a676bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ottenere aromi dall&#8217;ingrediente indicato richiede una grande quantit\u00e0 di materia prima.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">In alcuni casi, la resa dell&#8217;estrazione \u00e8 bassa, la disponibilit\u00e0 di frutta \u00e8 limitata e anche la stabilit\u00e0 dell&#8217;aroma pu\u00f2 essere compromessa.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Quando vengono utilizzati per miscele di t\u00e8, inoltre, c&#8217;\u00e8 una sfida in pi\u00f9. Il t\u00e8 stesso e gli altri ingredienti hanno un loro carattere, e quando vengono preparati con acqua molto calda, la resistenza dell&#8217;aroma viene messa alla prova.\u00a0\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93c427e e-flex e-con-boxed e-con e-child\" data-id=\"93c427e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-889f82b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"889f82b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewBox=\"0 0 192 192\"><defs><style> .cls-1 { fill: none; } .cls-2 { fill: #1d1d1b; } <\/style><\/defs><g id=\"medida\"><g><rect class=\"cls-1\" width=\"192\" height=\"192\"><\/rect><g><path class=\"cls-2\" d=\"M50.98,81.76h-15.81c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h15.81c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M64.9,53.79c1.37-1.37,1.37-3.58,0-4.95l-10.12-10.12c-1.37-1.37-3.58-1.37-4.95,0-1.37,1.37-1.37,3.58,0,4.95l10.12,10.12c.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03Z\"><\/path><path class=\"cls-2\" d=\"M145.27,38.72c-1.37-1.37-3.58-1.37-4.95,0l-10.12,10.12c-1.37,1.37-1.37,3.58,0,4.95,.68,.68,1.58,1.03,2.47,1.03s1.79-.34,2.47-1.03l10.12-10.12c1.37-1.37,1.37-3.58,0-4.95Z\"><\/path><path class=\"cls-2\" d=\"M97.75,42c1.93,0,3.5-1.57,3.5-3.5v-14.15c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5v14.15c0,1.93,1.57,3.5,3.5,3.5Z\"><\/path><path class=\"cls-2\" d=\"M156.83,81.76h-14.03c-1.93,0-3.5,1.57-3.5,3.5s1.57,3.5,3.5,3.5h14.03c1.93,0,3.5-1.57,3.5-3.5s-1.57-3.5-3.5-3.5Z\"><\/path><path class=\"cls-2\" d=\"M97.75,48.42c-19.84,0-35.98,16.14-35.98,35.98,0,5.06,.99,9.78,3.03,14.44,.96,2.2,2.35,4.65,3.82,7.25,2.14,3.78,4.57,8.07,5.66,11.69,5.01,16.67,2.59,32.29,2.56,32.45l-.05,.56c0,11.22,9.13,20.36,20.36,20.36s20.36-9.13,20.36-20.36l-.04-.56c-.01-.09-.83-5.44-.21-13.48,.08-.29,.13-.58,.13-.89,0-.1-.02-.19-.03-.29,.48-5.16,1.55-11.3,3.76-17.81,1.37-4.04,4.12-8.95,6.55-13.28,1.09-1.95,2.12-3.79,2.96-5.44,2.75-5.36,3.12-10.41,3.12-14.64,0-19.84-16.14-35.98-35.98-35.98Zm12.3,90.94c-.16,4.07,0,7.32,.19,9.41h-26.18c.21-2.1,.44-5.36,.39-9.41h25.6Zm-12.91,24.79c-5.6,0-10.4-3.48-12.38-8.38h24.76c-1.98,4.9-6.78,8.38-12.38,8.38Zm27.24-68.3c-.79,1.54-1.79,3.32-2.84,5.21-2.57,4.6-5.49,9.8-7.07,14.45-2.06,6.07-3.23,11.82-3.85,16.86h-9.68c.34-.54,.54-1.17,.54-1.86v-19.97c5.79-1.55,10.07-6.82,10.07-13.1,0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,3.62-2.95,6.57-6.57,6.57s-6.57-2.95-6.57-6.57c0-1.93-1.57-3.5-3.5-3.5s-3.5,1.57-3.5,3.5c0,6.27,4.28,11.55,10.07,13.1v19.97c0,.68,.2,1.32,.54,1.86h-10.93c-.44-5.05-1.37-10.74-3.14-16.6-1.31-4.37-3.95-9.02-6.27-13.12-1.38-2.44-2.68-4.74-3.5-6.6-1.64-3.76-2.44-7.56-2.44-11.64,0-15.98,13-28.98,28.98-28.98s28.98,13,28.98,28.98c0,4.87-.68,8.19-2.35,11.45Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eacdf7 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9eacdf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">In molte miscele di t\u00e8 convenzionali l'aroma pu\u00f2 \"mascherare\" il sapore degli altri ingredienti. Nel caso delle miscele certificate come biologiche, l'aroma apporta sapore come un ingrediente in pi\u00f9, senza coprire gli altri ingredienti e, in molti casi, essendo anche molto volatile. <\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61f4a88 elementor-widget elementor-widget-text-editor\" data-id=\"61f4a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questo aiuta a capire perch\u00e9 le miscele di t\u00e8 biologici aromatizzati richiedono un lavoro di formulazione pi\u00f9 complesso e perch\u00e9 non sempre possono offrire esattamente lo stesso impatto aromatico di un prodotto convenzionale.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8a58cf elementor-widget elementor-widget-heading\" data-id=\"e8a58cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'importanza di comprendere l'aromatizzazione nei t\u00e8 biologici per un professionista del t\u00e8\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4670be elementor-widget elementor-widget-text-editor\" data-id=\"b4670be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Per un&#8217;azienda del settore, comprendere gli aromi 95\/5 serve per acquistare meglio e anche per vendere meglio.<\/span><\/p><p><span style=\"font-weight: 400;\">Aiuta ad acquistare meglio perch\u00e9 permette di leggere con maggiore discernimento una ricetta, una scheda tecnica o un elenco di ingredienti. Non \u00e8 la stessa cosa trovare &#8220;<\/span><i><span style=\"font-weight: 400;\">aroma naturale<\/span><\/i><span style=\"font-weight: 400;\">&#8221; piuttosto che &#8220;<\/span><i><span style=\"font-weight: 400;\">aroma naturale di mango<\/span><\/i><span style=\"font-weight: 400;\">&#8220;. Nel secondo caso, il rapporto tra il sapore percepito e la sua origine \u00e8 molto pi\u00f9 diretto.<\/span><\/p><p><span style=\"font-weight: 400;\">Aiuta a vendere meglio perch\u00e9 sempre pi\u00f9 clienti chiedono da dove provengono gli aromi, cosa significhi realmente \u00abnaturale\u00bb e <\/span><b>perch\u00e9 un t\u00e8 biologico aromatizzato possa avere un prezzo diverso da quello convenzionale<\/b><span style=\"font-weight: 400;\">. Riuscire a spiegarlo con chiarezza trasmette seriet\u00e0 e valorizza il prodotto.<\/span><\/p><p><span style=\"font-weight: 400;\">E serve anche a posizionare meglio l&#8217;assortimento. In un negozio specializzato, una sala da t\u00e8, un marchio online o un progetto di marca propria, queste sfumature aiutano a sostenere una gamma premium e BIO pi\u00f9 coerente. In un mercato in cui molti prodotti sembrano simili a prima vista, saper spiegare bene queste differenze fa davvero la differenza.<\/span><\/p><p><span style=\"font-weight: 400;\">Nel nostro negozio online per professionisti del t\u00e8 troverai un&#8217;ampia selezione di <\/span><a href=\"https:\/\/b2b.alveus.eu\/it\/te.html?nxt_flavoured_filter=937&amp;nxt_monoblend=935&amp;nxt_organic_natural_filter=749\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">miscele di t\u00e8 e infusi aromatizzati biologici<\/span><\/a><span style=\"font-weight: 400;\">. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cosa significano realmente questi aromi e perch\u00e9 sono importanti nella formulazione di un t\u00e8 biologico.<\/p>\n","protected":false},"author":11,"featured_media":60370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[110],"tags":[],"class_list":["post-60394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-professionisti-del-te"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aromi utilizzati nei t\u00e8 biologici | Alveus<\/title>\n<meta name=\"description\" content=\"Tutto ci\u00f2 che serve per comprendere meglio gli aromi 95\/5 o FTNF nei t\u00e8 biologici e la loro funzione nella ricetta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aromi nei t\u00e8 biologici: cosa sono e perch\u00e9 sono importanti\" \/>\n<meta property=\"og:description\" content=\"Tutto ci\u00f2 che serve per comprendere meglio gli aromi 95\/5 o FTNF nei t\u00e8 biologici e la loro funzione nella ricetta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/\" \/>\n<meta property=\"og:site_name\" content=\"Alveus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alveusinternational\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T11:05:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T14:05:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alveus Blog Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alveus Blog Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/\"},\"author\":{\"name\":\"Alveus Blog Team\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#\\\/schema\\\/person\\\/6864b22051c6c128b3c72edaeac35855\"},\"headline\":\"Aromi nei t\u00e8 biologici: cosa sono e perch\u00e9 sono importanti\",\"datePublished\":\"2026-03-27T11:05:28+00:00\",\"dateModified\":\"2026-04-28T14:05:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/\"},\"wordCount\":1343,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alveus.eu\\\/wp-content\\\/uploads\\\/117_c.jpg\",\"articleSection\":[\"Professionisti del T\u00e9\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/\",\"url\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/\",\"name\":\"Aromi utilizzati nei t\u00e8 biologici | Alveus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alveus.eu\\\/wp-content\\\/uploads\\\/117_c.jpg\",\"datePublished\":\"2026-03-27T11:05:28+00:00\",\"dateModified\":\"2026-04-28T14:05:18+00:00\",\"description\":\"Tutto ci\u00f2 che serve per comprendere meglio gli aromi 95\\\/5 o FTNF nei t\u00e8 biologici e la loro funzione nella ricetta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alveus.eu\\\/wp-content\\\/uploads\\\/117_c.jpg\",\"contentUrl\":\"https:\\\/\\\/www.alveus.eu\\\/wp-content\\\/uploads\\\/117_c.jpg\",\"width\":900,\"height\":600,\"caption\":\"creazione di una miscela di t\u00e8\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/aromi-te-biologici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alveus.eu\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professionisti del T\u00e9\",\"item\":\"https:\\\/\\\/www.alveus.eu\\\/it\\\/blog\\\/category\\\/professionisti-del-te\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aromi nei t\u00e8 biologici: cosa sono e perch\u00e9 sono importanti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#website\",\"url\":\"https:\\\/\\\/www.alveus.eu\\\/it\",\"name\":\"Alveus\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alveus.eu\\\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#organization\",\"name\":\"Alveus\",\"alternateName\":\"Alveus Premium Teas\",\"url\":\"https:\\\/\\\/www.alveus.eu\\\/it\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alveus.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/alveus-logo-primary.png\",\"contentUrl\":\"https:\\\/\\\/www.alveus.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/alveus-logo-primary.png\",\"width\":248,\"height\":248,\"caption\":\"Alveus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alveusinternational\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alveustea\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/alveustea\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alveus.eu\\\/it#\\\/schema\\\/person\\\/6864b22051c6c128b3c72edaeac35855\",\"name\":\"Alveus Blog Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f951c832a9809c8d01d2ce4fa8bb10716ac4997c3cf93244fa19413f7d28b08e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f951c832a9809c8d01d2ce4fa8bb10716ac4997c3cf93244fa19413f7d28b08e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f951c832a9809c8d01d2ce4fa8bb10716ac4997c3cf93244fa19413f7d28b08e?s=96&d=mm&r=g\",\"caption\":\"Alveus Blog Team\"},\"description\":\"Editorial team formed by tea professionals from different countries. We are driven by our passion for tea and the dissemination of its culture.\",\"sameAs\":[\"https:\\\/\\\/www.alveus.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aromi utilizzati nei t\u00e8 biologici | Alveus","description":"Tutto ci\u00f2 che serve per comprendere meglio gli aromi 95\/5 o FTNF nei t\u00e8 biologici e la loro funzione nella ricetta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/","og_locale":"it_IT","og_type":"article","og_title":"Aromi nei t\u00e8 biologici: cosa sono e perch\u00e9 sono importanti","og_description":"Tutto ci\u00f2 che serve per comprendere meglio gli aromi 95\/5 o FTNF nei t\u00e8 biologici e la loro funzione nella ricetta.","og_url":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/","og_site_name":"Alveus","article_publisher":"https:\/\/www.facebook.com\/alveusinternational\/","article_published_time":"2026-03-27T11:05:28+00:00","article_modified_time":"2026-04-28T14:05:18+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_c.jpg","type":"image\/jpeg"}],"author":"Alveus Blog Team","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Alveus Blog Team","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#article","isPartOf":{"@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/"},"author":{"name":"Alveus Blog Team","@id":"https:\/\/www.alveus.eu\/it#\/schema\/person\/6864b22051c6c128b3c72edaeac35855"},"headline":"Aromi nei t\u00e8 biologici: cosa sono e perch\u00e9 sono importanti","datePublished":"2026-03-27T11:05:28+00:00","dateModified":"2026-04-28T14:05:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/"},"wordCount":1343,"commentCount":0,"publisher":{"@id":"https:\/\/www.alveus.eu\/it#organization"},"image":{"@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_c.jpg","articleSection":["Professionisti del T\u00e9"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/","url":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/","name":"Aromi utilizzati nei t\u00e8 biologici | Alveus","isPartOf":{"@id":"https:\/\/www.alveus.eu\/it#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#primaryimage"},"image":{"@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_c.jpg","datePublished":"2026-03-27T11:05:28+00:00","dateModified":"2026-04-28T14:05:18+00:00","description":"Tutto ci\u00f2 che serve per comprendere meglio gli aromi 95\/5 o FTNF nei t\u00e8 biologici e la loro funzione nella ricetta.","breadcrumb":{"@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#primaryimage","url":"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_c.jpg","contentUrl":"https:\/\/www.alveus.eu\/wp-content\/uploads\/117_c.jpg","width":900,"height":600,"caption":"creazione di una miscela di t\u00e8"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alveus.eu\/it\/blog\/aromi-te-biologici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alveus.eu\/it"},{"@type":"ListItem","position":2,"name":"Professionisti del T\u00e9","item":"https:\/\/www.alveus.eu\/it\/blog\/category\/professionisti-del-te\/"},{"@type":"ListItem","position":3,"name":"Aromi nei t\u00e8 biologici: cosa sono e perch\u00e9 sono importanti"}]},{"@type":"WebSite","@id":"https:\/\/www.alveus.eu\/it#website","url":"https:\/\/www.alveus.eu\/it","name":"Alveus","description":"","publisher":{"@id":"https:\/\/www.alveus.eu\/it#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alveus.eu\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.alveus.eu\/it#organization","name":"Alveus","alternateName":"Alveus Premium Teas","url":"https:\/\/www.alveus.eu\/it","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alveus.eu\/it#\/schema\/logo\/image\/","url":"https:\/\/www.alveus.eu\/wp-content\/uploads\/2023\/07\/alveus-logo-primary.png","contentUrl":"https:\/\/www.alveus.eu\/wp-content\/uploads\/2023\/07\/alveus-logo-primary.png","width":248,"height":248,"caption":"Alveus"},"image":{"@id":"https:\/\/www.alveus.eu\/it#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alveusinternational\/","https:\/\/www.instagram.com\/alveustea\/","https:\/\/de.linkedin.com\/company\/alveustea"]},{"@type":"Person","@id":"https:\/\/www.alveus.eu\/it#\/schema\/person\/6864b22051c6c128b3c72edaeac35855","name":"Alveus Blog Team","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f951c832a9809c8d01d2ce4fa8bb10716ac4997c3cf93244fa19413f7d28b08e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f951c832a9809c8d01d2ce4fa8bb10716ac4997c3cf93244fa19413f7d28b08e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f951c832a9809c8d01d2ce4fa8bb10716ac4997c3cf93244fa19413f7d28b08e?s=96&d=mm&r=g","caption":"Alveus Blog Team"},"description":"Editorial team formed by tea professionals from different countries. We are driven by our passion for tea and the dissemination of its culture.","sameAs":["https:\/\/www.alveus.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/posts\/60394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/comments?post=60394"}],"version-history":[{"count":4,"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/posts\/60394\/revisions"}],"predecessor-version":[{"id":60621,"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/posts\/60394\/revisions\/60621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/media\/60370"}],"wp:attachment":[{"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/media?parent=60394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/categories?post=60394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alveus.eu\/it\/wp-json\/wp\/v2\/tags?post=60394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}